{"id":9381,"date":"2025-03-27T16:09:47","date_gmt":"2025-03-27T16:09:47","guid":{"rendered":"https:\/\/tbs.ac.th\/sites\/?p=9381"},"modified":"2025-03-28T00:38:13","modified_gmt":"2025-03-28T00:38:13","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%8a%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%a1%e0%b8%b5%e0%b8%aa%e0%b8%b4%e0%b8%97%e0%b8%98-7","status":"publish","type":"post","link":"https:\/\/tbs.ac.th\/sites\/archives\/9381","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e48\u0e2d\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19 \u0e21.4 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2568 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e01\u0e15\u0e34"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-vivid-red-background-color has-background wp-element-button\" href=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2025\/03\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e30\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e2d\u0e1a-\u0e21.4-\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b-2568.pdf\">\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e2d\u0e1a\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e31\u0e49\u0e19 \u0e21.4 \u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e01\u0e15\u0e34 2568<\/a><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"50\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2024\/12\/Untitled-2.jpg\" alt=\"\" class=\"wp-image-9089\" style=\"width:400px;height:auto\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2024\/12\/Untitled-2.jpg 1000w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2024\/12\/Untitled-2-300x15.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2024\/12\/Untitled-2-500x25.jpg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":9379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[22,53],"tags":[],"_links":{"self":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/posts\/9381"}],"collection":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/comments?post=9381"}],"version-history":[{"count":2,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/posts\/9381\/revisions"}],"predecessor-version":[{"id":9384,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/posts\/9381\/revisions\/9384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/media\/9379"}],"wp:attachment":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/media?parent=9381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/categories?post=9381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/tags?post=9381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}