{"id":2473,"date":"2019-12-02T10:20:19","date_gmt":"2019-12-02T10:20:19","guid":{"rendered":"http:\/\/tbs.ac.th\/sites\/?page_id=2473"},"modified":"2020-01-01T06:20:58","modified_gmt":"2020-01-01T06:20:58","slug":"elementor-2473","status":"publish","type":"page","link":"https:\/\/tbs.ac.th\/sites\/elementor-2473","title":{"rendered":"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 Powerpoint \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2473\" class=\"elementor elementor-2473\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d0761 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34d0761\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54e9cb7\" data-id=\"54e9cb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e74c9f elementor-widget elementor-widget-heading\" data-id=\"9e74c9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 Powerpoinr \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0c787b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0c787b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0de3bc\" data-id=\"a0de3bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bdf003 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7bdf003\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab37aed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab37aed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a7aaa9\" data-id=\"5a7aaa9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-246797a elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"246797a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e0a\u0e38\u0e142-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 ppt \u0e0a\u0e38\u0e142\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 ppt \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912-300x169.jpg\" alt=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0183e3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0183e3c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39c9dff\" data-id=\"39c9dff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68762e6 elementor-widget elementor-widget-text-editor\" data-id=\"68762e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h3>\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e20\u0e32\u0e1e\u0e02\u0e49\u0e32\u0e07\u0e25\u0e48\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e04\u0e21\u0e0a\u0e31\u0e14\u00a0<\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-838d857 elementor-widget elementor-widget-image-gallery\" data-id=\"838d857\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-2473 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1912-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1911-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e1910-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e199-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e198-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e197-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e196-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e195-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e194-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e193-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 ppt \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"838d857\" data-elementor-lightbox-title=\"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 ppt \u0e0a\u0e38\u0e142\" href='https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e0a\u0e38\u0e142.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e0a\u0e38\u0e142-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e0a\u0e38\u0e142-150x150.jpg 150w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e0a\u0e38\u0e142-300x300.jpg 300w, https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/2019\/12\/\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07-ppt-\u0e0a\u0e38\u0e142-70x70.jpg 70w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94ae32b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94ae32b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb0a880\" data-id=\"fb0a880\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4d8a9b elementor-widget elementor-widget-text-editor\" data-id=\"b4d8a9b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><a href=\"https:\/\/tbs.ac.th\/sites\/elementor-2473\">\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e07\u0e32\u0e19 Powerpoint \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35<\/a><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 Powerpoinr <\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"rankMath":{"parentDomain":"tbs.ac.th","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"elementor-2473","permalinkFormat":"https:\/\/tbs.ac.th\/sites\/%pagename%","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/tbs.ac.th\/sites\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"\u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 Powerpoint \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e43\u0e2b\u0e49\u0e14\u0e39\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e07\u0e32\u0e19\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d","focusKeywords":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 \u0e1e\u0e37\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07 Powerpoint","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"admin","titleTemplate":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 %page% %sep% %sitename%","descriptionTemplate":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":[],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/tbs.ac.th\/sites","objectID":2473,"objectType":"post","locale":"th","localeFull":"th","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/tbs.ac.th\/sites\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/tbs\/domains\/tbs.ac.th\/public_html\/sites\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/tbs.ac.th\/sites\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/tbs\/domains\/tbs.ac.th\/public_html\/sites\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/tbs.ac.th\/sites\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":true,"autoSuggestKeywords":true,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Ftbs.ac.th%2Fsites&r=https%3A%2F%2Ftbs.ac.th%2Fsites%2Fwp-json%2Fwp%2Fv2%2Fpages%2F2473%3Fnonce%3D69ca88698d","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/tbs.ac.th\/sites\/wp-content\/uploads\/\/2025\/01\/\u0e15\u0e23\u0e32\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35-150x150.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/tbs.ac.th\/sites\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":[],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 Thanyaburi School \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e15 4 %page% %sep% %sitedesc%","description":"\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e18\u0e31\u0e0d\u0e1a\u0e38\u0e23\u0e35 Thanyaburi School \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e02\u0e15 4","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/pages\/2473"}],"collection":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/comments?post=2473"}],"version-history":[{"count":5,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/pages\/2473\/revisions"}],"predecessor-version":[{"id":2672,"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/pages\/2473\/revisions\/2672"}],"wp:attachment":[{"href":"https:\/\/tbs.ac.th\/sites\/wp-json\/wp\/v2\/media?parent=2473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}